{"id":1129,"date":"2024-05-02T16:09:19","date_gmt":"2024-05-02T20:09:19","guid":{"rendered":"https:\/\/bedrock4.com\/?p=1129"},"modified":"2024-05-03T14:12:33","modified_gmt":"2024-05-03T18:12:33","slug":"comment-augmenter-la-valeur-dun-programme-de-conformite","status":"publish","type":"post","link":"https:\/\/bedrock4.com\/fr\/comment-augmenter-la-valeur-dun-programme-de-conformite\/","title":{"rendered":"Comment augmenter la valeur d&rsquo;un programme de conformit\u00e9 ?"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbligne\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.0&Prime; _module_preset=\u00a0\u00bb18e5836c-bc9f-4d18-a7d4-45b873c0be54&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h4>Comment transformer les contr\u00f4les en une efficacit\u00e9 accrue ?<\/h4>\n<ul>\n<li>Cr\u00e9ez le processus et les proc\u00e9dures les plus simples que votre \u00e9quipe peut et veut suivre.<\/li>\n<li>Identifier les indicateurs pertinents pour mesurer la production et la qualit\u00e9<\/li>\n<\/ul>\n<p>Identifier et \u00e9valuer les possibilit\u00e9s d&rsquo;automatiser les proc\u00e9dures manuelles stables :<\/p>\n<ul>\n<li>L&rsquo;investissement dans les outils d&rsquo;automatisation permettra-t-il d&rsquo;augmenter la production ou la qualit\u00e9 ? (id\u00e9alement les deux)\n<ul>\n<li>Les outils identifi\u00e9s sont-ils d\u00e9j\u00e0 utilis\u00e9s ailleurs dans l&rsquo;organisation ? L&rsquo;exp\u00e9rience peut aider \u00e0 identifier les obstacles et les limites potentiels.<\/li>\n<\/ul>\n<\/li>\n<li>Qui est concern\u00e9 par l&rsquo;automatisation ?\n<ul>\n<li>Auront-ils besoin d&rsquo;une formation pour s&rsquo;adapter \u00e0 l&rsquo;automatisation ou pour effectuer de nouvelles activit\u00e9s ?<\/li>\n<\/ul>\n<\/li>\n<li>Tenez compte des co\u00fbts d&rsquo;entretien courants\n<ul>\n<li>Contrats de maintenance pour vous assurer l&rsquo;acc\u00e8s aux mises \u00e0 jour de s\u00e9curit\u00e9 et aux nouvelles versions<\/li>\n<li>Une personne devra assurer la maintenance de la technologie d&rsquo;automatisation<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Les proc\u00e9dures ne sont pas la fin de la cr\u00e9ativit\u00e9 et de l&rsquo;adaptabilit\u00e9. Une proc\u00e9dure est la version professionnelle d&rsquo;une habitude. Pensez \u00e0 votre routine matinale :<\/p>\n<ol>\n<li>Eteignez l&rsquo;alam<\/li>\n<li>Sortez du lit<\/li>\n<li>Aller aux toilettes<\/li>\n<li>Brossez-vous les dents, etc.<\/li>\n<\/ol>\n<p>Vous ne pensez pas vraiment \u00e0 ce que vous faites, et c&rsquo;est une bonne chose. Votre esprit se pr\u00e9pare pour la journ\u00e9e \u00e0 venir, et c&rsquo;est l\u00e0 que votre \u00e9nergie doit \u00eatre concentr\u00e9e.<\/p>\n<p>Pensez maintenant \u00e0 la fa\u00e7on dont vous pourriez commencer votre journ\u00e9e de travail au bureau :<\/p>\n<ol>\n<li>Entrez dans le b\u00e2timent<\/li>\n<li>Passez votre badge<\/li>\n<li>Prenez un caf\u00e9, saluez vos coll\u00e8gues<\/li>\n<li>Marcher jusqu&rsquo;\u00e0 votre lieu de travail ou votre bureau<\/li>\n<li>Connectez-vous \u00e0 votre ordinateur<\/li>\n<li>Ouvrez votre courrier \u00e9lectronique, votre navigateur, etc.<\/li>\n<\/ol>\n<p>Une proc\u00e9dure simple ne signifie pas qu&rsquo;elle comporte moins de 10 \u00e9tapes. Cela signifie qu&rsquo;une personne ayant des connaissances de base sur le travail peut ex\u00e9cuter les t\u00e2ches avec succ\u00e8s.<\/p>\n<p>Exemple : Demandes de r\u00e9initialisation de mot de passe<\/p>\n<p>Situation actuelle : Le personnel peut appeler le service d&rsquo;assistance, envoyer une demande \u00e0 partir de son adresse \u00e9lectronique personnelle, utiliser WhatsApp pour contacter son administrateur pr\u00e9f\u00e9r\u00e9, etc.<\/p>\n<p><strong>Nouvelle proc\u00e9dure :<\/strong><\/p>\n<ul>\n<li>Le personnel DOIT contacter le service d&rsquo;assistance en utilisant le num\u00e9ro, l&rsquo;adresse \u00e9lectronique ou le formulaire de contact pr\u00e9vu \u00e0 cet effet. Toutes les autres demandes doivent \u00eatre redirig\u00e9es.<\/li>\n<li>Le service d&rsquo;assistance :<\/li>\n<li>Cr\u00e9e une demande li\u00e9e \u00e0 la personne.<\/li>\n<li>Confirme l&rsquo;identit\u00e9 de la personne :<\/li>\n<li>Avoir acc\u00e8s aux informations fournies par chaque personne, sauvegard\u00e9es dans un endroit central et s\u00e9curis\u00e9. Il ne doit pas s&rsquo;agir d&rsquo;informations personnelles, mais d&rsquo;informations confidentielles que la personne a partag\u00e9es dans le seul but de s&rsquo;identifier. Par exemple, une s\u00e9rie de questions et de r\u00e9ponses de leur choix.<\/li>\n<li>NOTE : Si l&rsquo;identification \u00e9choue, la demande est transform\u00e9e en incident de s\u00e9curit\u00e9.<\/li>\n<li>Choisit un nouveau mot de passe al\u00e9atoire, g\u00e9n\u00e9r\u00e9 par random.org<\/li>\n<li>Le demandeur confirme qu&rsquo;il peut acc\u00e9der au site, au syst\u00e8me ou \u00e0 l&rsquo;application.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Mesures :<\/strong><\/p>\n<ul>\n<li>Nombre de r\u00e9initialisations de mot de passe par p\u00e9riode<\/li>\n<li>Nombre d&rsquo;incidents de s\u00e9curit\u00e9 g\u00e9n\u00e9r\u00e9s par des demandes de r\u00e9initialisation de mot de passe<\/li>\n<li>Nombre de fois o\u00f9 le demandeur a \u00e9chou\u00e9 dans l&rsquo;utilisation du nouveau mot de passe<\/li>\n<\/ul>\n<ul><\/ul>\n<p>Bien que cette proc\u00e9dure soit fonctionnelle, il peut devenir fastidieux, au fur et \u00e0 mesure que l&rsquo;organisation se d\u00e9veloppe, d&rsquo;avoir un nombre sans cesse croissant de demandes de r\u00e9initialisation de mot de passe. Cependant, le service d&rsquo;assistance et de cybers\u00e9curit\u00e9 devrait surveiller les param\u00e8tres (entre autres) pour voir s&rsquo;il y a des possibilit\u00e9s d&rsquo;am\u00e9lioration, comme par exemple :<\/p>\n<ul>\n<li>Portails de gestion des comptes en libre-service<\/li>\n<li>Passkeys pour remplacer compl\u00e8tement le mot de passe<\/li>\n<\/ul>\n<p>Le processus d\u00e9crit ci-dessus serait acceptable pour une attestation SOC 2, et les am\u00e9liorations devraient \u00eatre conformes \u00e0 tous les cadres et r\u00e8glements, pour autant que je sache.<\/p>\n<p>Ai-je oubli\u00e9 quelque chose ?<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment transformer les contr\u00f4les en une efficacit\u00e9 accrue ? Cr\u00e9ez le processus et les proc\u00e9dures les plus simples que votre \u00e9quipe peut et veut suivre. Identifier les indicateurs pertinents pour mesurer la production et la qualit\u00e9 Identifier et \u00e9valuer les possibilit\u00e9s d&rsquo;automatiser les proc\u00e9dures manuelles stables : L&rsquo;investissement dans les outils d&rsquo;automatisation permettra-t-il d&rsquo;augmenter la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[37],"tags":[],"class_list":["post-1129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compliance-fr"],"_links":{"self":[{"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/posts\/1129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/comments?post=1129"}],"version-history":[{"count":9,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/posts\/1129\/revisions"}],"predecessor-version":[{"id":1237,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/posts\/1129\/revisions\/1237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/media\/1037"}],"wp:attachment":[{"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/media?parent=1129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/categories?post=1129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/tags?post=1129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}