{"id":1120,"date":"2024-05-03T11:18:51","date_gmt":"2024-05-03T15:18:51","guid":{"rendered":"https:\/\/bedrock4.com\/?p=1120"},"modified":"2024-05-03T14:06:18","modified_gmt":"2024-05-03T18:06:18","slug":"la-conformite-ne-devrait-pas-etre-difficile","status":"publish","type":"post","link":"https:\/\/bedrock4.com\/fr\/la-conformite-ne-devrait-pas-etre-difficile\/","title":{"rendered":"La conformit\u00e9 ne devrait pas \u00eatre difficile"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<!-- divi:paragraph --><\/p>\n<p>J&rsquo;ai parl\u00e9 de la d\u00e9couverte des zones bleues dans mon pr\u00e9c\u00e9dent article (lien), qui sont des endroits dans le monde o\u00f9 les gens ont tendance \u00e0 vivre plus longtemps, non pas parce que c&rsquo;est ce qu&rsquo;ils souhaitent. Ils vivent plus longtemps parce que leur vie est plus heureuse et remplie d&rsquo;objectifs.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>L&rsquo;allongement de la dur\u00e9e de vie est le r\u00e9sultat de l&rsquo;environnement de la zone bleue, qui comprend la communaut\u00e9&#8230;.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Nous avons d\u00e9j\u00e0 d\u00e9crit la conformit\u00e9 comme le r\u00e9sultat d&rsquo;une s\u00e9rie d&rsquo;activit\u00e9s qui r\u00e9pondent \u00e0 des exigences d\u00e9finies. Alors, le respect des r\u00e8gles semble-t-il si difficile \u00e0 atteindre ?&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Nous cr\u00e9ons des programmes de conformit\u00e9, investissons des dizaines de milliers de dollars pour pousser les gens \u00e0 documenter les processus, les proc\u00e9dures op\u00e9rationnelles standard (POS), les matrices de responsabilit\u00e9.&nbsp;&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Nous demandons ensuite \u00e0 nos \u00e9quipes d&rsquo;effectuer le travail conform\u00e9ment \u00e0 tout ce qu&rsquo;elles ont document\u00e9, faute de quoi de mauvaises choses se produiront \u00e0 l&rsquo;arriv\u00e9e de l&rsquo;auditeur.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Ensuite, l&rsquo;audit. Ce moment redoutable o\u00f9 tout le monde est soudainement indisponible pour une r\u00e9union, tellement ils sont occup\u00e9s \u00e0 accomplir des t\u00e2ches essentielles. Tout pour ne pas avoir \u00e0 parler \u00e0 l&rsquo;auditeur.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Cela vous rappelle quelque chose ?&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Pour ceux d&rsquo;entre vous qui travaillent sur des programmes de conformit\u00e9 ou qui sont responsables de certains contr\u00f4les, saviez-vous que, pour la plupart, ils ne sont pas grav\u00e9s dans le marbre ?&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Si certains cadres, comme PCI DSS, ont \u00e9volu\u00e9 vers des lignes directrices prescriptives de mise en \u0153uvre, beaucoup sont des descriptions de haut niveau d&rsquo;objectifs recommand\u00e9s. Ces objectifs doivent \u00eatre adapt\u00e9s aux r\u00e9alit\u00e9s de votre organisation.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Par exemple, SOC 2 recommande une \u00e9valuation annuelle des employ\u00e9s. Si ce contr\u00f4le est inclus dans le champ d&rsquo;application de l&rsquo;audit, ils vous demanderont de prouver que les \u00e9valuations sont effectu\u00e9es, que le retour d&rsquo;information est fourni et que des plans de formation sont \u00e9labor\u00e9s si n\u00e9cessaire.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Que se passe-t-il si vous n&rsquo;effectuez pas d&rsquo;\u00e9valuation annuelle ? Que se passe-t-il si vous ne les aimez pas, si vous ne pensez pas qu&rsquo;ils fonctionnent et si vous pr\u00e9f\u00e9rez une autre m\u00e9thode ?&nbsp;&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Parfait ! Changez le contr\u00f4le !&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Demandez \u00e0 l&rsquo;auditeur de modifier le contr\u00f4le. Comment ?&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Expliquez-leur comment vous fournissez un retour d&rsquo;information \u00e0 votre personnel.&nbsp;&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Comment vous les aidez \u00e0 d\u00e9velopper leurs comp\u00e9tences&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Comment ils apprennent&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Comment ils \u00e9voluent au sein de l&rsquo;entreprise&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>L&rsquo;objectif de l&rsquo;auditeur est de prouver que vous disposez d&rsquo;un processus efficace d&rsquo;\u00e9valuation et de soutien des employ\u00e9s. C&rsquo;est tout.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Vous d\u00e9cidez de ce qui fonctionne ou non.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Cependant, une fois que vous avez pris votre d\u00e9cision, \u00e9crivez-la et continuez \u00e0 inciter les gens \u00e0 faire ce qui doit \u00eatre fait. Si l&rsquo;incitation ne fonctionne pas, r\u00e9\u00e9valuez le processus, la proc\u00e9dure normalis\u00e9e ou la liste de contr\u00f4le. Adaptez-vous lorsque c&rsquo;est possible.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Le respect des r\u00e8gles est plus facile lorsqu&rsquo;il est int\u00e9gr\u00e9 \u00e0 vos activit\u00e9s quotidiennes.&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph --><\/p>\n<p>Gardez votre \u00e9quipe concentr\u00e9e sur les objectifs&nbsp;<\/p>\n<p><!-- \/divi:paragraph -->[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai parl\u00e9 de la d\u00e9couverte des zones bleues dans mon pr\u00e9c\u00e9dent article (lien), qui sont des endroits dans le monde o\u00f9 les gens ont tendance \u00e0 vivre plus longtemps, non pas parce que c&rsquo;est ce qu&rsquo;ils souhaitent. Ils vivent plus longtemps parce que leur vie est plus heureuse et remplie d&rsquo;objectifs.&nbsp; L&rsquo;allongement de la dur\u00e9e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[37],"tags":[],"class_list":["post-1120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compliance-fr"],"_links":{"self":[{"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/posts\/1120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/comments?post=1120"}],"version-history":[{"count":6,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/posts\/1120\/revisions"}],"predecessor-version":[{"id":1202,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/posts\/1120\/revisions\/1202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/media\/1027"}],"wp:attachment":[{"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/media?parent=1120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/categories?post=1120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bedrock4.com\/fr\/wp-json\/wp\/v2\/tags?post=1120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}